{"id":6370,"date":"2025-04-22T09:12:21","date_gmt":"2025-04-22T09:12:21","guid":{"rendered":"https:\/\/dydon.ai\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/"},"modified":"2025-05-04T16:38:32","modified_gmt":"2025-05-04T16:38:32","slug":"stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable","status":"publish","type":"post","link":"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/","title":{"rendered":"Stop-the-Clock: le r\u00f4le-cl\u00e9 de l\u2019IA pour les banques en mati\u00e8re de finance durable"},"content":{"rendered":"\n<p>La r\u00e9cente directive europ\u00e9enne instaurant un m\u00e9canisme suspensif, dit <strong><a href=\"https:\/\/www.consilium.europa.eu\/fr\/press\/press-releases\/2025\/04\/14\/simplification-council-gives-final-green-light-on-the-stop-the-clock-mechanism-to-boost-eu-competitiveness-and-provide-legal-certainty-to-businesses\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00ab\u202fStop-the-Clock\u202f\u00bb<\/a>,<\/strong> approuv\u00e9e d\u00e9finitivement par le Conseil le 14 avril 2025, ouvre une fen\u00eatre de man\u0153uvre mais soul\u00e8ve aussi des enjeux strat\u00e9giques pour les institutions financi\u00e8res.<\/p>\n\n<p><strong>Cette directive reporte les obligations de reporting et de diligence raisonnable pour certaines entreprises au titre de la directive sur le reporting de durabilit\u00e9 des entreprises (CSRD), du r\u00e8glement europ\u00e9en sur la taxonomie et de la directive sur le devoir de vigilance des entreprises en mati\u00e8re de durabilit\u00e9 (CS3D).<\/strong> Elle s\u2019inscrit dans la <a href=\"https:\/\/dydon.ai\/fr\/legislation-omnibus-ce-qui-change-pour-la-csrd-et-la-taxonomie-europeenne\/\" target=\"_blank\" rel=\"noreferrer noopener\">l\u00e9gislation \u00ab Omnibus I \u00bb<\/a>, pr\u00e9sent\u00e9e par l\u2019UE et adopt\u00e9 par la Commission europ\u00e9enne fin f\u00e9vrier 2025, dont le but est de simplifier le cadre l\u00e9gislatif europ\u00e9en en mati\u00e8re de d\u00e9veloppement durable. <\/p>\n\n<p>La mesure introduit <strong>deux reports r\u00e9glementaires majeurs <\/strong>:<\/p>\n\n<p>\u2013 <strong>Une extension de deux ans pour la mise en \u0153uvre du CSRD<\/strong>, accordant plus de temps aux grandes entreprises n\u2019ayant pas encore entam\u00e9 leur reporting <strong>(vague 2)<\/strong> et aux <strong>PME cot\u00e9es en bourse (vague 3)<\/strong>. En d\u2019autres termes, les grandes entreprises et les banques ont d\u00e9sormais jusqu\u2019en 2028 pour publier leur reporting CSRD au titre de l\u2019exercice 2027, tandis que les PME cot\u00e9es suivront un an plus tard. <\/p>\n\n<p>\u2013 <strong>Un report d\u2019un an de la phase initiale de mise en \u0153uvre et de la date limite de transposition de la CS3D<\/strong>, d\u00e9cal\u00e9e de juillet 2027 \u00e0 juillet 2028, impactant principalement les plus grandes entreprises de l\u2019Union europ\u00e9enne.<\/p>\n\n<p>Cette d\u00e9cision r\u00e9pond directement aux enjeux soulev\u00e9s dans les rapports d\u2019Enrico Letta (<a target=\"_blank\" rel=\"noreferrer noopener\" href=\"https:\/\/www.consilium.europa.eu\/media\/ny3j24sm\/much-more-than-a-market-report-by-enrico-letta.pdf\">\u00ab\u202fBien plus qu\u2019un march\u00e9\u202f\u00bb<\/a>, en anglais) et de Mario Draghi (<a target=\"_blank\" rel=\"noreferrer noopener\" href=\"https:\/\/commission.europa.eu\/topics\/eu-competitiveness\/draghi-report_en\">\u00ab\u202fL\u2019avenir de la comp\u00e9titivit\u00e9 europ\u00e9enne\u202f\u00bb<\/a>), qui insistent sur la n\u00e9cessit\u00e9 urgente d\u2019all\u00e9ger la charge administrative pesant sur les entreprises. La Commission europ\u00e9enne, sous le second mandat d\u2019Ursula von der Leyen, concentre d\u00e9sormais ses efforts sur la r\u00e9duction de la bureaucratie et du fardeau d\u00e9claratif, notamment pour les PME, tout en poursuivant les objectifs de durabilit\u00e9 du Pacte vert pour l\u2019Europe. <\/p>\n\n<p>La loi a \u00e9t\u00e9 publi\u00e9e au <a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/FR\/TXT\/?uri=CELEX:32025L0794\" target=\"_blank\" rel=\"noreferrer noopener\">Journal officiel de l\u2019Union europ\u00e9enne le 16 avril 2025<\/a> et est entr\u00e9e en vigueur le 17 avril 2025. Elle devra d\u00e9sormais \u00eatre transpos\u00e9e dans le droit national, les \u00c9tats membres disposant d\u2019un d\u00e9lai jusqu\u2019au 31 d\u00e9cembre 2025.   <\/p>\n\n<h2 class=\"wp-block-heading\">Reporting et finance durable : simple conformit\u00e9 ou levier de diff\u00e9renciation concurrentielle ?<\/h2>\n\n<p>Pour les dirigeants d\u2019institutions financi\u00e8res confront\u00e9s \u00e0 ce temps de pause r\u00e9glementaire autour de la CSRD \u2014 et indirectement de la taxonomie europ\u00e9enne \u2014 dans le cadre de la finance durable de l\u2019UE, ce n\u2019est pas un signal pour lever le pied, mais une occasion strat\u00e9gique majeure de prendre l\u2019avantage.<\/p>\n\n<h3 class=\"wp-block-heading\">1. De la conformit\u00e9 formelle \u00e0 une v\u00e9ritable strat\u00e9gie<\/h3>\n\n<p>De nombreuses banques europ\u00e9ennes ont d\u2019abord abord\u00e9 l\u2019ESG, la taxonomie europ\u00e9enne et le reporting en mati\u00e8re de finance durable comme un simple exercice de conformit\u00e9 \u2014 une obligation \u00e0 cocher, dict\u00e9e par la pression r\u00e9glementaire venue de Bruxelles. Le report des \u00e9ch\u00e9ances cr\u00e9e un espace pour passer d\u2019une posture r\u00e9active \u00e0 une strat\u00e9gie proactive, o\u00f9 la durabilit\u00e9 devient une valeur centrale de l\u2019entreprise et un v\u00e9ritable levier de diff\u00e9renciation sur le march\u00e9. <\/p>\n\n<p>Plut\u00f4t que de simplement r\u00e9pondre aux exigences minimales de reporting en finance durable, les banques peuvent d\u00e9sormais b\u00e2tir des cadres solides de finance durable, int\u00e9gr\u00e9s \u00e0 leurs op\u00e9rations, \u00e0 leur gestion des risques, \u00e0 leurs pratiques de cr\u00e9dit et \u00e0 leurs relations clients \u00e0 travers les \u00c9tats membres de l\u2019UE. Cette base sera pr\u00e9cieuse, quelle que soit l\u2019\u00e9volution future des exigences en mati\u00e8re de reporting ESG. <\/p>\n\n<h3 class=\"wp-block-heading\">2. Faire la preuve d\u2019une strat\u00e9gie verte authentique<\/h3>\n\n<p>Lors de la pr\u00e9sentation du paquet Omnibus par la Commission europ\u00e9enne, 11 grandes entreprises internationales ont cosign\u00e9 <a target=\"_blank\" rel=\"noreferrer noopener\" href=\"https:\/\/sustainabilitymag.com\/articles\/what-is-the-eus-omnibus-why-are-major-companies-against-it\">une lettre ouverte critiquant ces changements<\/a>, exprimant leurs craintes quant \u00e0 une possible incertitude autour du reporting de durabilit\u00e9. Mais, en r\u00e9alit\u00e9, elles avaient probablement compris que le moment serait mal choisi pour reculer dans la transition vers une \u00e9conomie et un syst\u00e8me financier plus durables.<\/p>\n\n<p>Les institutions financi\u00e8res disposent aujourd\u2019hui d\u2019une occasion unique de prouver \u00e0 leurs clients, investisseurs et parties prenantes que leurs d\u00e9marches en mati\u00e8re de finance durable ne rel\u00e8vent pas d\u2019une simple contrainte r\u00e9glementaire, mais traduisent de v\u00e9ritables priorit\u00e9s strat\u00e9giques, pleinement align\u00e9es sur les objectifs du Pacte vert pour l\u2019Europe.<\/p>\n\n<h3 class=\"wp-block-heading\">3. Prendre une longueur d\u2019avance gr\u00e2ce \u00e0 l\u2019anticipation<\/h3>\n\n<p>Les institutions financi\u00e8res qui sauront exploiter intelligemment ce d\u00e9lai suppl\u00e9mentaire prendront de l\u2019avance sur leurs concurrents lorsque les exigences de reporting entreront pleinement en vigueur dans l\u2019UE. Comme l\u2019ont soulign\u00e9 plusieurs experts en d\u00e9veloppement durable apr\u00e8s le vote du Parlement europ\u00e9en, cette p\u00e9riode de transition doit permettre de renforcer l\u2019infrastructure des donn\u00e9es ESG et les capacit\u00e9s de reporting, afin d\u2019\u00eatre pr\u00eates pour la conformit\u00e9 \u00e0 l\u2019horizon 2028. <\/p>\n\n<p>Cette pr\u00e9paration implique la mise en place de syst\u00e8mes de collecte et d\u2019analyse des donn\u00e9es de durabilit\u00e9, la formation des \u00e9quipes aux standards ESG, l\u2019engagement avec les clients sur leurs performances en mati\u00e8re de durabilit\u00e9 au regard des crit\u00e8res europ\u00e9ens, ainsi que l\u2019adaptation des structures de gouvernance pour porter des strat\u00e9gies ESG align\u00e9es sur les exigences du r\u00e8glement sur la taxonomie et les objectifs environnementaux de l\u2019UE.<\/p>\n\n<h2 class=\"wp-block-heading\">IA : l\u2019outil indispensable pour se conformer au reporting de durabilit\u00e9 dans l\u2019UE<\/h2>\n\n<p>Malgr\u00e9 les reports actuels, la directive \u00ab\u202fStop-the-Clock\u202f\u00bb s\u2019inscrit dans un processus r\u00e9glementaire en constante \u00e9volution. Les dynamiques li\u00e9es \u00e0 la politique climatique, aux initiatives scientifiques europ\u00e9ennes et aux attentes soci\u00e9tales indiquent que la r\u00e9glementation en manti\u00e8re de finance durable continuera de changer. <\/p>\n\n<p>Cette instabilit\u00e9 r\u00e9glementaire rend indispensable une approche souple et fond\u00e9e sur l\u2019intelligence artificielle pour les banques op\u00e9rant dans l\u2019Union europ\u00e9enne. <a target=\"_blank\" rel=\"noreferrer noopener\" href=\"https:\/\/dydon.ai\/fr\/taxonomie-europeenne-les-8-fonctionnalites-incontournables-dune-plateforme-de-reporting-esg\/\">Les solutions d\u2019IA offrent des avantages majeurs<\/a> : elles permettent <strong>d\u2019extraire avec pr\u00e9cision des donn\u00e9es cl\u00e9s issues de documents techniques<\/strong>, et de traiter efficacement les volumes importants d\u2019informations requis pour assurer la conformit\u00e9.<\/p>\n\n<p>En cas de donn\u00e9es incompl\u00e8tes \u2014 situation fr\u00e9quente avec les PME ou les petits \u00e9tablissements financiers \u2014 <strong>les outils d\u2019IA facilitent les calculs d\u2019\u00e9missions carbone <\/strong>et l\u2019application des crit\u00e8res techniques de s\u00e9lection, tout en <strong>automatisant la lecture documentaire et la collecte de donn\u00e9es<\/strong> via le traitement du langage naturel.<\/p>\n\n<p>L\u2019\u00e9valuation des risques est \u00e9galement renforc\u00e9e gr\u00e2ce \u00e0 <strong>l\u2019analyse g\u00e9olocalis\u00e9e<\/strong>, <strong>qui croise les coordonn\u00e9es des projets avec des bases de donn\u00e9es sur les risques g\u00e9ologiques et climatiques<\/strong>, pour fournir des \u00e9valuations pr\u00e9cises conformes aux <strong>crit\u00e8res DNSH (Do No Significant Harm)<\/strong>.<\/p>\n\n<p>La flexibilit\u00e9 des architectures d\u2019IA permet aux institutions de <strong>produire un reporting pr\u00eat pour l\u2019audit<\/strong>, d\u2019int\u00e9grer facilement les \u00e9volutions r\u00e9glementaires, et d\u2019assurer une <strong>continuit\u00e9 de conformit\u00e9, sans repenser leurs syst\u00e8mes en profondeur<\/strong>.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/dydon.ai\/wp-content\/uploads\/2024\/09\/Immagine-5-logo-taxotool-v2-1024x576.jpg\" alt=\"Logiciel d'IA pour le reporting de taxonomie de l'UE\" class=\"wp-image-5503\" srcset=\"https:\/\/dydon.ai\/wp-content\/uploads\/2024\/09\/Immagine-5-logo-taxotool-v2-1024x576.jpg 1024w, https:\/\/dydon.ai\/wp-content\/uploads\/2024\/09\/Immagine-5-logo-taxotool-v2-300x169.jpg 300w, https:\/\/dydon.ai\/wp-content\/uploads\/2024\/09\/Immagine-5-logo-taxotool-v2-768x432.jpg 768w, https:\/\/dydon.ai\/wp-content\/uploads\/2024\/09\/Immagine-5-logo-taxotool-v2-1536x864.jpg 1536w, https:\/\/dydon.ai\/wp-content\/uploads\/2024\/09\/Immagine-5-logo-taxotool-v2.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">Les solutions Dydon AI pour le reporting de durabilit\u00e9 et la taxonomie europ\u00e9enne<\/h2>\n\n<p>Chez <a target=\"_blank\" rel=\"noreferrer noopener\" href=\"https:\/\/dydon.ai\/fr\/\">Dydon AI<\/a>, nous avons d\u00e9velopp\u00e9 des solutions d\u2019intelligence artificielle innovantes, sp\u00e9cialement con\u00e7ues pour accompagner les banques et institutions financi\u00e8res europ\u00e9ennes. Notre gamme d\u2019outils se distingue par sa sophistication et son efficacit\u00e9 op\u00e9rationnelle \u2014 que ce soit pour le reporting li\u00e9 \u00e0 la taxonomie europ\u00e9enne ou au-del\u00e0. <\/p>\n\n<p>Notre produit phare, le <a href=\"https:\/\/dydon.ai\/fr\/solutions\/fintech-et-regtech\/taxo-tool-taxonomie-de-lue\/\" target=\"_blank\" rel=\"noreferrer noopener\">TAXO TOOL<\/a>, d\u00e9velopp\u00e9 en collaboration avec le Bundesverband \u00d6ffentlicher Banken Deutschlands (V\u00d6B) et V\u00d6B-Service GmbH, a re\u00e7u le prix de la \u00ab Meilleure solution de donn\u00e9es taxonomiques ESG \u00bb aux European ESG Insight Awards. Il est d\u00e9j\u00e0 utilis\u00e9 depuis 2022 par des banques de premier plan pour optimiser leur processus de reporting selon la taxonomie de l\u2019UE.<\/p>\n\n<h3 class=\"wp-block-heading\">Au-del\u00e0 de la taxonomie europ\u00e9enne : une suite compl\u00e8te de solutions d\u2019IA<\/h3>\n\n<p>Au-del\u00e0 du TAXO TOOL, nous proposons d\u2019autres solutions d\u2019intelligence artificielle con\u00e7ues pour le cadre r\u00e9glementaire europ\u00e9en, afin d\u2019aider les institutions financi\u00e8res et les entreprises \u00e0 d\u00e9velopper des strat\u00e9gies solides en mati\u00e8re de reporting durable et de conformit\u00e9 :<\/p>\n\n<ul>\n<li><strong>Suivi des \u00e9carts de conformit\u00e9 : <\/strong>extrait et compare avec pr\u00e9cision les donn\u00e9es et contenus entre documents r\u00e9glementaires externes et politiques internes, afin d\u2019identifier rapidement les ajustements n\u00e9cessaires pour r\u00e9pondre aux nouvelles exigences.<\/li>\n\n\n\n<li><strong>Lecture de documents et capture de donn\u00e9es ESG :<\/strong> automatise le traitement des documents en lisant, extrayant et structurant les donn\u00e9es ESG pertinentes \u00e0 l\u2019aide d\u2019agents IA sp\u00e9cialement entra\u00een\u00e9s sur les donn\u00e9es en mati\u00e8re de durabilit\u00e9.<\/li>\n\n\n\n<li><strong>GPT priv\u00e9 : <\/strong>b\u00e9n\u00e9ficiez d\u2019un accompagnement en intelligence artificielle tout en prot\u00e9geant vos donn\u00e9es et celles de vos clients ; entra\u00eenez des GPT priv\u00e9s sur vos documents et th\u00e9matiques (ex.\u202f: reporting de durabilit\u00e9).<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Une opportunit\u00e9 d\u00e9cisive pour les banques europ\u00e9ennes<\/h2>\n\n<p>La directive \u00ab\u202fStop-the-Clock\u202f\u00bb de l\u2019UE offre aux institutions financi\u00e8res un d\u00e9lais pr\u00e9cieux, mais c\u2019est la mani\u00e8re dont ce temps suppl\u00e9mentaire sera utilis\u00e9 qui distinguera les visionnaires des suiveurs dans le domaine de la finance durable. Plut\u00f4t que de ralentir leurs initiatives, les banques leaders doivent acc\u00e9l\u00e9rer leurs efforts, soutenues par des outils d\u2019IA avanc\u00e9s qui rendent leurs strat\u00e9gies de durabilit\u00e9 plus efficaces et adaptables. <\/p>\n\n<p>Dans un contexte de transformation g\u00e9opolitique et de transition r\u00e9glementaire, <strong>la question n\u2019est pas de savoir si le d\u00e9veloppement durable restera une question centrale dans l\u2019UE \u2014 elle le sera \u00e0 coup s\u00fbr \u2014 mais quelles institutions financi\u00e8res sauront profiter de cette p\u00e9riode pour d\u00e9velopper les comp\u00e9tences technologiques et l\u2019expertise organisationnelle n\u00e9cessaires pour r\u00e9ussir dans un avenir o\u00f9 la durabilit\u00e9 sera au c\u0153ur de la performance.<\/strong><\/p>\n\n<p>Les banques qui s\u2019imposeront comme leaders seront celles qui verront au-del\u00e0 de la conformit\u00e9, reconnaissant dans la durabilit\u00e9 une opportunit\u00e9 strat\u00e9gique, et sauront mobiliser l\u2019intelligence artificielle pour concr\u00e9tiser leur vision. Le compte \u00e0 rebours r\u00e9glementaire est suspendu, mais la dynamique vers la finance durable se poursuit : c\u2019est maintenant que les banques doivent maintenir le cap pour montrer la voie quand les \u00e9ch\u00e9ances r\u00e9glementaires reprendront. <\/p>\n\n<h3 class=\"wp-block-heading\">D\u00e9couvrez comment notre IA peut vous aider<\/h3>\n\n<script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js-eu1.hsforms.net\/forms\/embed\/v2.js\"><\/script><script>hbspt.forms.create({\n    portalId: \"144536670\",\n    formId: \"f5bfb05f-d713-41a1-997d-813360a98beb\"\n  });\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>La r\u00e9cente directive europ\u00e9enne instaurant un m\u00e9canisme suspensif, dit \u00ab\u202fStop-the-Clock\u202f\u00bb, approuv\u00e9e d\u00e9finitivement par le Conseil le 14 avril 2025, ouvre une fen\u00eatre de man\u0153uvre mais soul\u00e8ve aussi des enjeux strat\u00e9giques pour les institutions financi\u00e8res. Cette directive reporte les obligations de reporting et de diligence raisonnable pour certaines entreprises au titre de la directive sur le&#8230;<\/p>\n","protected":false},"author":4,"featured_media":6346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_show_sidebar_banner":"","_show_download_button":"","footnotes":""},"categories":[8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Stop-the-Clock: Les banques utilisent l&#039;IA pour promouvoir la finance durable<\/title>\n<meta name=\"description\" content=\"L\u2019\u00e9volution constante de la r\u00e9glementation impose aux banques une approche souple et guid\u00e9e par l\u2019IA de la finance durable \u2014 d\u00e9couvrez comment dans cet article.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stop-the-Clock: Les banques utilisent l&#039;IA pour promouvoir la finance durable\" \/>\n<meta property=\"og:description\" content=\"L\u2019\u00e9volution constante de la r\u00e9glementation impose aux banques une approche souple et guid\u00e9e par l\u2019IA de la finance durable \u2014 d\u00e9couvrez comment dans cet article.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-22T09:12:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-04T16:38:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/stg.dydon.ai\/wp-content\/uploads\/2025\/04\/Beyond-Stop-the-clock-EU-Taxonomy-reporting-with-AI-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/\",\"url\":\"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/\",\"name\":\"Stop-the-Clock: Les banques utilisent l'IA pour promouvoir la finance durable\",\"isPartOf\":{\"@id\":\"https:\/\/dydon.ai\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dydon.ai\/wp-content\/uploads\/2025\/04\/Beyond-Stop-the-clock-EU-Taxonomy-reporting-with-AI-.jpg\",\"datePublished\":\"2025-04-22T09:12:21+00:00\",\"dateModified\":\"2025-05-04T16:38:32+00:00\",\"author\":{\"@id\":\"https:\/\/dydon.ai\/fr\/#\/schema\/person\/b6c03d6c1b49cc12e35fc6f95de28253\"},\"description\":\"L\u2019\u00e9volution constante de la r\u00e9glementation impose aux banques une approche souple et guid\u00e9e par l\u2019IA de la finance durable \u2014 d\u00e9couvrez comment dans cet article.\",\"breadcrumb\":{\"@id\":\"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/#primaryimage\",\"url\":\"https:\/\/dydon.ai\/wp-content\/uploads\/2025\/04\/Beyond-Stop-the-clock-EU-Taxonomy-reporting-with-AI-.jpg\",\"contentUrl\":\"https:\/\/dydon.ai\/wp-content\/uploads\/2025\/04\/Beyond-Stop-the-clock-EU-Taxonomy-reporting-with-AI-.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Beyond Stop-the-clock: how banks can leap ahead in sustainable finance with AI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dydon.ai\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stop-the-Clock: le r\u00f4le-cl\u00e9 de l\u2019IA pour les banques en mati\u00e8re de finance durable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dydon.ai\/fr\/#website\",\"url\":\"https:\/\/dydon.ai\/fr\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dydon.ai\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dydon.ai\/fr\/#\/schema\/person\/b6c03d6c1b49cc12e35fc6f95de28253\",\"name\":\"Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dydon.ai\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/83720290758f9313e87aa801fc89cf13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/83720290758f9313e87aa801fc89cf13?s=96&d=mm&r=g\",\"caption\":\"Silva\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stop-the-Clock: Les banques utilisent l'IA pour promouvoir la finance durable","description":"L\u2019\u00e9volution constante de la r\u00e9glementation impose aux banques une approche souple et guid\u00e9e par l\u2019IA de la finance durable \u2014 d\u00e9couvrez comment dans cet article.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/","og_locale":"fr_FR","og_type":"article","og_title":"Stop-the-Clock: Les banques utilisent l'IA pour promouvoir la finance durable","og_description":"L\u2019\u00e9volution constante de la r\u00e9glementation impose aux banques une approche souple et guid\u00e9e par l\u2019IA de la finance durable \u2014 d\u00e9couvrez comment dans cet article.","og_url":"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/","article_published_time":"2025-04-22T09:12:21+00:00","article_modified_time":"2025-05-04T16:38:32+00:00","og_image":[{"width":1920,"height":1080,"url":"http:\/\/stg.dydon.ai\/wp-content\/uploads\/2025\/04\/Beyond-Stop-the-clock-EU-Taxonomy-reporting-with-AI-.jpg","type":"image\/jpeg"}],"author":"Silva","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Silva","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/","url":"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/","name":"Stop-the-Clock: Les banques utilisent l'IA pour promouvoir la finance durable","isPartOf":{"@id":"https:\/\/dydon.ai\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/#primaryimage"},"image":{"@id":"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/#primaryimage"},"thumbnailUrl":"https:\/\/dydon.ai\/wp-content\/uploads\/2025\/04\/Beyond-Stop-the-clock-EU-Taxonomy-reporting-with-AI-.jpg","datePublished":"2025-04-22T09:12:21+00:00","dateModified":"2025-05-04T16:38:32+00:00","author":{"@id":"https:\/\/dydon.ai\/fr\/#\/schema\/person\/b6c03d6c1b49cc12e35fc6f95de28253"},"description":"L\u2019\u00e9volution constante de la r\u00e9glementation impose aux banques une approche souple et guid\u00e9e par l\u2019IA de la finance durable \u2014 d\u00e9couvrez comment dans cet article.","breadcrumb":{"@id":"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/#primaryimage","url":"https:\/\/dydon.ai\/wp-content\/uploads\/2025\/04\/Beyond-Stop-the-clock-EU-Taxonomy-reporting-with-AI-.jpg","contentUrl":"https:\/\/dydon.ai\/wp-content\/uploads\/2025\/04\/Beyond-Stop-the-clock-EU-Taxonomy-reporting-with-AI-.jpg","width":1920,"height":1080,"caption":"Beyond Stop-the-clock: how banks can leap ahead in sustainable finance with AI"},{"@type":"BreadcrumbList","@id":"https:\/\/dydon.ai\/fr\/stop-the-clock-le-role-cle-de-lia-pour-les-banques-en-matiere-de-finance-durable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dydon.ai\/fr\/"},{"@type":"ListItem","position":2,"name":"Stop-the-Clock: le r\u00f4le-cl\u00e9 de l\u2019IA pour les banques en mati\u00e8re de finance durable"}]},{"@type":"WebSite","@id":"https:\/\/dydon.ai\/fr\/#website","url":"https:\/\/dydon.ai\/fr\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dydon.ai\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/dydon.ai\/fr\/#\/schema\/person\/b6c03d6c1b49cc12e35fc6f95de28253","name":"Silva","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dydon.ai\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/83720290758f9313e87aa801fc89cf13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83720290758f9313e87aa801fc89cf13?s=96&d=mm&r=g","caption":"Silva"}}]}},"taxonomy_info":{"category":[{"value":8,"label":"Non classifi\u00e9(e)"}]},"featured_image_src_large":["https:\/\/dydon.ai\/wp-content\/uploads\/2025\/04\/Beyond-Stop-the-clock-EU-Taxonomy-reporting-with-AI--1024x576.jpg",1024,576,true],"author_info":{"display_name":"Silva","author_link":"https:\/\/dydon.ai\/fr\/author\/silva\/"},"comment_info":0,"category_info":[{"term_id":8,"name":"Non classifi\u00e9(e)","slug":"non-classifiee","term_group":0,"term_taxonomy_id":8,"taxonomy":"category","description":"","parent":0,"count":37,"filter":"raw","cat_ID":8,"category_count":37,"category_description":"","cat_name":"Non classifi\u00e9(e)","category_nicename":"non-classifiee","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/dydon.ai\/fr\/wp-json\/wp\/v2\/posts\/6370"}],"collection":[{"href":"https:\/\/dydon.ai\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dydon.ai\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dydon.ai\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dydon.ai\/fr\/wp-json\/wp\/v2\/comments?post=6370"}],"version-history":[{"count":1,"href":"https:\/\/dydon.ai\/fr\/wp-json\/wp\/v2\/posts\/6370\/revisions"}],"predecessor-version":[{"id":6371,"href":"https:\/\/dydon.ai\/fr\/wp-json\/wp\/v2\/posts\/6370\/revisions\/6371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dydon.ai\/fr\/wp-json\/wp\/v2\/media\/6346"}],"wp:attachment":[{"href":"https:\/\/dydon.ai\/fr\/wp-json\/wp\/v2\/media?parent=6370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dydon.ai\/fr\/wp-json\/wp\/v2\/categories?post=6370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dydon.ai\/fr\/wp-json\/wp\/v2\/tags?post=6370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}