{"id":4527,"date":"2024-04-30T10:19:21","date_gmt":"2024-04-30T10:19:21","guid":{"rendered":"https:\/\/dydon.ai\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/"},"modified":"2025-01-06T09:57:51","modified_gmt":"2025-01-06T09:57:51","slug":"das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen","status":"publish","type":"post","link":"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/","title":{"rendered":"Das Ziel der EU-Taxonomie f\u00fcr die Kreislaufwirtschaft: Auswirkungen auf Immobilien und Bauwesen"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Die Europ\u00e4ische Union befindet sich auf einer ehrgeizigen und notwendigen Reise, um das Zusammenspiel von Wirtschaftswachstum und \u00f6kologischer Nachhaltigkeit neu zu definieren. In ihrem Bestreben, das Wirtschaftswachstum vom Verbrauch nicht erneuerbarer Ressourcen abzukoppeln, hat sich die EU zum Ziel gesetzt, ihren materiellen Fu\u00dfabdruck deutlich zu verringern.  <\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Ausgehend von einem Richtwert von 14 Tonnen pro Kopf im Jahr 2015 wird eine Reduzierung um 50% bis 2030 und um 75% bis 2050 angestrebt. Dar\u00fcber hinaus haben wir uns zum Ziel gesetzt, den Anteil der Verwendung von Kreislaufmaterial bis 2030 auf mindestens 25% zu erh\u00f6hen.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Im Mittelpunkt des Wandels zur Nachhaltigkeit steht die <a href=\"https:\/\/dydon.ai\/navigating-eu-taxonomy-reporting-timeline-kpis-and-best-practices\/\">EU-Taxonomie<\/a> f\u00fcr nachhaltige Aktivit\u00e4ten, ein Rahmenwerk, das Investitionen in \u00f6kologisch nachhaltige Wirtschaftsprojekte lenken soll.<\/h2>\n\n\n\n<p>Ein wichtiger gesetzgeberischer Schritt, den die Kommission am 27. Juni 2023 verabschiedet hat, ist das Paket neuer Ma\u00dfnahmen zur Aktualisierung und Ausweitung der Anwendung der EU-Taxonomie mit <strong>vier neuen Umweltzielen<\/strong>, die zusammen als <a href=\"https:\/\/dydon.ai\/?p=4816\" target=\"_blank\" rel=\"noreferrer noopener\">&#8222;Taxo4&#8220;<\/a> bekannt sind. Darunter ist der <strong>\u00dcbergang zu einer Kreislaufwirtschaft<\/strong> (Ziel Nr. 4) ein wichtiges Ziel, insbesondere f\u00fcr die Immobilien- und Bauwirtschaft, auf das wir uns in diesem Artikel konzentrieren werden.<\/p>\n\n\n\n<p>Diese Industrien, die f\u00fcr ihren erheblichen \u00f6kologischen Fu\u00dfabdruck bekannt sind, sind nicht nur wegen ihres betr\u00e4chtlichen Ressourcenverbrauchs und Abfallaufkommens von Bedeutung, sondern auch wegen ihrer Auswirkungen auf die Wirtschaft, die lokale Besch\u00e4ftigung und die Lebensqualit\u00e4t.<\/p>\n\n\n\n<p>Die bebaute Umwelt ist ein gro\u00dfer Ressourcenverbraucher und verbraucht <a href=\"https:\/\/single-market-economy.ec.europa.eu\/industry\/sustainability\/buildings-and-construction_en\" target=\"_blank\" rel=\"noreferrer noopener\">etwa 50% aller weltweit gewonnenen Materialien<\/a>. Gleichzeitig entwickelt <strong>sich der Bausektor zu einer Hauptabfallquelle, die \u00fcber 35% des gesamten Abfallaufkommens in der EU erzeugt.<\/strong> Dieses Szenario erfordert dringend die Einf\u00fchrung nachhaltiger Bau- und Renovierungspraktiken, um die Umweltbelastungen in diesen Sektoren zu verringern.<\/p>\n\n\n\n<p>Au\u00dferdem <strong>sind die Treibhausgasemissionen (THG) des Bausektors beachtlich<\/strong>. <strong>Die Emissionen aus der Materialgewinnung, der Herstellung von Bauprodukten und den Bauprozessen tragen in der EU zu 5-12% der gesamten nationalen Treibhausgasemissionen bei. <\/strong> <\/p>\n\n\n\n<p>Diese Herausforderung birgt jedoch auch gro\u00dfe Chancen. Durch die Verbesserung der Materialeffizienz k\u00f6nnten bis zu 80% dieser Emissionen eingespart werden. Dies unterstreicht die unverzichtbare Rolle der Kreislaufwirtschaft im Rahmen der EU-Taxonomieverordnung, die die Bedeutung der Ausweitung der  <strong>Haltbarkeit, Reparierbarkeit, Aufr\u00fcstbarkeit, Wiederverwendbarkeit und Wiederverwertbarkeit<\/strong>und gleichzeitig die Ressourceneffizienz zu verbessern und Abfall zu minimieren &#8211; in der Immobilien- und Baubranche und dar\u00fcber hinaus.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Bewertung der Anpassung der Baut\u00e4tigkeiten an das Ziel der EU-Taxonomie f\u00fcr die Kreislaufwirtschaft<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"460\" src=\"https:\/\/dydon.ai\/wp-content\/uploads\/2024\/04\/sustainable-buildings-eu-taxonomy-reporting-small.jpg\" alt=\"\" class=\"wp-image-4406\" style=\"width:840px;height:auto\" srcset=\"https:\/\/dydon.ai\/wp-content\/uploads\/2024\/04\/sustainable-buildings-eu-taxonomy-reporting-small.jpg 760w, https:\/\/dydon.ai\/wp-content\/uploads\/2024\/04\/sustainable-buildings-eu-taxonomy-reporting-small-300x182.jpg 300w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/figure>\n\n\n\n<p>Um festzustellen, ob die wirtschaftlichen Aktivit\u00e4ten mit der EU-Taxonomie \u00fcbereinstimmen, m\u00fcssen sie einen dreistufigen Angleichungsprozess durchlaufen, der in den folgenden Abschnitten beschrieben wird: substanzieller Beitrag, DNSH (Do No Significant Harm) und Einhaltung der Mindestgarantien. Die gleichen Schritte gelten auch f\u00fcr das Ziel der EU, den \u00dcbergang zu einer Kreislaufwirtschaft zu schaffen.<\/p>\n\n\n\n<p>Um mit dem Ziel der EU-Taxonomie f\u00fcr den &#8222;\u00dcbergang zu einer Kreislaufwirtschaft&#8220; \u00fcbereinzustimmen, m\u00fcssen wirtschaftliche Aktivit\u00e4ten im Zusammenhang mit dem Bau, der Renovierung und dem Abriss von Geb\u00e4uden bestimmte <strong>technische Screening-Kriterien (TSC<\/strong>) erf\u00fcllen. Diese Kriterien sollen sicherstellen, dass die Aktivit\u00e4t einen wesentlichen Beitrag zum \u00dcbergang zu einer Kreislaufwirtschaft leistet, indem sie Nachhaltigkeit, Abfallvermeidung und die Reduzierung von Treibhausgasemissionen f\u00f6rdert.  <\/p>\n\n\n\n<p>Auch wenn der Bau neuer Geb\u00e4ude und die Renovierung bestehender Geb\u00e4ude bereits unter die Ziele der Klimaanpassung und des Klimaschutzes fielen, gibt es einige neue Aktivit\u00e4ten im Zusammenhang mit Immobilien und Bauwesen, die unter das neue Ziel der Kreislaufwirtschaft fallen.<\/p>\n\n\n\n<p>Hier finden Sie die in der EU-Taxonomie f\u00fcr das Ziel &#8222;\u00dcbergang zu einer Kreislaufwirtschaft&#8220; festgelegten wirtschaftlichen <a href=\"https:\/\/www.epra.com\/application\/files\/2417\/0172\/1969\/EPRA_EU_Taxonomy_Guide_Update_December_2023.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Aktivit\u00e4ten, die f\u00fcr das Baugewerbe und die Immobilienwirtschaft relevant sind<\/a>:  <\/p>\n\n\n\n<ul>\n<li><strong>Wirtschaftliche Aktivit\u00e4t 3.1. &#8222;Bau von neuen Geb\u00e4uden&#8220;<\/strong>  (NACE-Codes F41.1, F4.2, F43),<\/li>\n\n\n\n<li><strong>Wirtschaftliche Aktivit\u00e4t 3.2. &#8222;Renovierung von bestehenden Geb\u00e4uden&#8220;<\/strong>  (NACE-Codes F41, F43),<\/li>\n\n\n\n<li><strong>Wirtschaftszweig 3.3 \u00b3eAbriss von Geb\u00e4uden und anderen Bauwerken\u00b3c<\/strong> (NACE-Code F43.).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Erheblicher Beitrag: Technische Screening-Kriterien f\u00fcr die Kreislaufwirtschaft in der Bau- und Immobilienbranche<\/h3>\n\n\n\n<p>Eine der wichtigsten Voraussetzungen f\u00fcr die Einstufung als wesentlicher Beitrag zum Ziel der Kreislaufwirtschaft ist die Bewertung des <strong>Treibhauspotenzials (GWP<\/strong> ) der an der Wirtschaftst\u00e4tigkeit beteiligten Geb\u00e4ude w\u00e4hrend ihres gesamten Lebenszyklus.  <strong>Dabei werden die Treibhausgasemissionen berechnet, die mit jeder Phase des Lebenszyklus eines Geb\u00e4udes verbunden sind, vom Bau bis zum Abriss.<\/strong>  Indem sie die Quellen von Treibhausgasemissionen identifizieren und angehen, k\u00f6nnen Wirtschaftsakteure Schritte unternehmen, um ihre Umweltauswirkungen zu reduzieren und die Nachhaltigkeit zu f\u00f6rdern.  <\/p>\n\n\n\n<p>Dar\u00fcber hinaus verlangen die TSC f\u00fcr wirtschaftliche Aktivit\u00e4ten im Zusammenhang mit dem Bau, der Renovierung und dem Abriss von Geb\u00e4uden auch die Einhaltung von Standards f\u00fcr die Abfallbehandlung, den Erhalt des urspr\u00fcnglichen Geb\u00e4udes, wo dies m\u00f6glich ist, und die Verwendung von Sekund\u00e4rrohstoffen anstelle von Prim\u00e4rrohstoffen.  <\/p>\n\n\n\n<p>Diese Ma\u00dfnahmen zielen darauf ab, die Abfallproduktion zu minimieren, Ressourcen zu schonen und die Kreislaufnutzung von Materialien zu f\u00f6rdern, um die Ziele der Kreislaufwirtschaft zu erreichen.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Was kann getan werden, um den Bau neuer Geb\u00e4ude nachhaltiger und konformer mit der EU-Taxonomie zu gestalten?<\/h2>\n\n\n\n<p>Im Bereich der Kreislaufwirtschaft erfordert die Entwicklung von Bauprojekten f\u00fcr Wohn- und Nichtwohngeb\u00e4ude einen umfassenden Ansatz, bei dem finanzielle, technische und physische Ressourcen zusammengef\u00fchrt werden.  <\/p>\n\n\n\n<p>In diesem Zusammenhang wurden <strong>mit den Kriterien der EU-Taxonomie<\/strong> f\u00fcr einen <strong>&#8222;wesentlichen Beitrag&#8220;<\/strong> zur Kreislaufwirtschaft beim Bau neuer Geb\u00e4ude strenge Richtlinien zur Verbesserung der Nachhaltigkeit in diesem Sektor festgelegt:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>1. Abfallentsorgung:<\/strong> <\/h3>\n\n\n\n<p>Die Einhaltung der EU-Abfallgesetzgebung und des EU-Protokolls \u00fcber die Entsorgung von Bau- und Abbruchabf\u00e4llen ist obligatorisch. Ziel ist die <strong>Wiederverwendung oder das Recycling von mindestens 90 % (nach Masse) der nicht gef\u00e4hrlichen Bau- und Abbruchabf\u00e4lle, ausgenommen nat\u00fcrlich vorkommende Materialien<\/strong>.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2. Offenlegung des globalen Erw\u00e4rmungspotenzials (GWP):<\/strong> <\/h3>\n\n\n\n<p>Das Lebenszyklus-GWP des Geb\u00e4udes muss berechnet und auf Anfrage f\u00fcr Investoren und Kunden offengelegt werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3. Kreisf\u00f6rmiges Design und Konstruktion:  <\/strong><\/h3>\n\n\n\n<p>Einbeziehung von Design f\u00fcr Anpassungsf\u00e4higkeit und Dekonstruktion zur Unterst\u00fctzung der Kreislaufwirtschaft.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4. Minimierung der Prim\u00e4rrohstoffe:<\/strong> <\/h3>\n\n\n\n<p>Der <strong>Verbrauch von Prim\u00e4rrohstoffen wird minimiert, indem<\/strong> <strong>H\u00f6chstgrenzen f\u00fcr verschiedene Materialien festgelegt werden: <\/strong>Beton und Stein (70%), Ziegel und Keramik (70%), biobasierte Materialien (80%), Glas und mineralische Isolierung (70%), nicht-biobasierte Kunststoffe (50%), Metalle (30%) und Gips (65%).  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5. Digitale Dokumentation:<\/strong> <\/h3>\n\n\n\n<p>Die Eigenschaften des Geb\u00e4udes, einschlie\u00dflich der verwendeten Materialien und Komponenten, m\u00fcssen f\u00fcr die k\u00fcnftige Wartung und Wiederverwendung elektronisch dokumentiert werden, wobei die EN ISO 22057:2022 f\u00fcr Umweltproduktdeklarationen (EPDs) genutzt wird. Diese Informationen sollten f\u00fcr Anleger und Kunden zug\u00e4nglich sein.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wie Sie die Einhaltung der EU-Taxonomie in der Bau- und Immobilienbranche mit Dydon AI automatisieren k\u00f6nnen<\/h2>\n\n\n\n<p>F\u00fcr Bau- und Immobilienunternehmen stellt die Anpassung an die Ziele der EU-Taxonomie f\u00fcr die Kreislaufwirtschaft eine komplexe Herausforderung dar, insbesondere bei der Verwaltung von Daten, der Nachhaltigkeitsberichterstattung und der Sicherstellung der Einhaltung anderer Anforderungen.  <\/p>\n\n\n\n<p><a href=\"https:\/\/dydon.ai\/de\/?p=4717\">Dydon AI nutzt fortschrittliche KI-Technologien &#8211; einschlie\u00dflich<\/a>Large Language Models (LLMs), Retrieval-Augmented Generation (RAG) und Natural Language Processing (NLP) &#8211; um diese Herausforderungen effektiv zu bew\u00e4ltigen und die Genauigkeit, Effizienz und Einhaltung der EU-Vorschriften zu verbessern.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"460\" src=\"https:\/\/dydon.ai\/wp-content\/uploads\/2022\/06\/lacking-data-sme-eu-taxonomy.jpg\" alt=\"\" class=\"wp-image-2454\" srcset=\"https:\/\/dydon.ai\/wp-content\/uploads\/2022\/06\/lacking-data-sme-eu-taxonomy.jpg 760w, https:\/\/dydon.ai\/wp-content\/uploads\/2022\/06\/lacking-data-sme-eu-taxonomy-300x182.jpg 300w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Erh\u00f6hte Genauigkeit bei der Compliance-Berichterstattung<\/strong> <\/h3>\n\n\n\n<p>Durch LLMs und RAG liefert <a href=\"https:\/\/dydon.ai\/de\/\">Dydon AI<\/a> pr\u00e4zise Datenanalysen und -extraktionen, die f\u00fcr die Erf\u00fcllung der Anforderungen der EU-Taxonomie entscheidend sind. Dies ist besonders vorteilhaft f\u00fcr die Handhabung der umfangreichen Dokumentation und der erforderlichen Nachhaltigkeitskennzahlen und vereinfacht den Berichtsprozess.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Automatisierte Datenextraktion<\/strong><\/h3>\n\n\n\n<p>Die KI-Technologie von Dydon eignet sich hervorragend zum Extrahieren wichtiger Informationen aus technischen Dokumenten. Diese Funktion ist der Schl\u00fcssel, um die Einhaltung der Ziele der Kreislaufwirtschaft nachzuweisen, den manuellen Aufwand erheblich zu verringern und sicherzustellen, dass Projekte die EU-Nachhaltigkeitsstandards erf\u00fcllen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Unterst\u00fctzung f\u00fcr technische Screening-Kriterien (TSC)<\/strong><\/h3>\n\n\n\n<p>Die TSCs der EU-Taxonomie sind f\u00fcr die Bewertung der Nachhaltigkeit unerl\u00e4sslich. Dydon AI unterst\u00fctzt Unternehmen bei der Schlie\u00dfung von Datenl\u00fccken mit Berechnungstools, die wichtige Metriken wie CO\u2082-Emissionen und andere Screening-Kriterien absch\u00e4tzen und so die Einhaltung von Standards der Kreislaufwirtschaft unterst\u00fctzen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Umfassende Risikobewertungen f\u00fcr nachhaltige Entwicklung<\/strong><\/h3>\n\n\n\n<p>Durch die Integration von Daten von <strong>Munich Re<\/strong> bietet Dydon AI detaillierte klimatische und geologische Risikobewertungen. Diese Funktionalit\u00e4t ist entscheidend f\u00fcr die Entwicklung widerstandsf\u00e4higer und nachhaltiger Immobilien und hilft der Industrie, potenzielle Nachhaltigkeitsrisiken im Einklang mit den Prinzipien der Klimaanpassung und der Kreislaufwirtschaft proaktiv anzugehen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Erkl\u00e4rbare KI: KI mit dem Fokus auf Transparenz einsetzen<\/h2>\n\n\n\n<p>In so komplexen und regulierten Branchen wie dem Bau- und Immobiliensektor sind Transparenz und Vertrauensw\u00fcrdigkeit von KI-gesteuerten Prozessen unerl\u00e4sslich. Das Engagement von Dydon AI f\u00fcr <strong>erkl\u00e4rbare KI (XAI)<\/strong> stellt sicher, dass die Stakeholder Klarheit und Vertrauen in die von unseren Algorithmen generierten Erkenntnisse haben. Dieses Ma\u00df an Transparenz ist von entscheidender Bedeutung, um die Ziele der EU-Taxonomie f\u00fcr die Kreislaufwirtschaft sicher zu erreichen. So k\u00f6nnen Unternehmen fundierte Entscheidungen treffen und ihr Engagement f\u00fcr nachhaltige Entwicklungspraktiken unter Beweis stellen.<\/p>\n\n\n\n<p>Durch den Einsatz der innovativen L\u00f6sungen von Dydon AI sind Bau- und Immobilienunternehmen besser ger\u00fcstet, um die Herausforderungen der Kriterien der EU-Taxonomie f\u00fcr die Kreislaufwirtschaft zu meistern. Unsere Technologie rationalisiert nicht nur den Prozess der Einhaltung von Vorschriften, sondern f\u00f6rdert auch die Integration nachhaltiger Praktiken und weist so den Weg in eine gr\u00fcnere Zukunft in der Immobilien- und Baubranche.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vereinbaren Sie eine kostenlose Demo mit einem unserer Experten<\/h2>\n\n\n\n<script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js-eu1.hsforms.net\/forms\/embed\/v2.js\"><\/script>\n<script>\n  hbspt.forms.create({\n    portalId: \"144536670\",\n    formId: \"f5bfb05f-d713-41a1-997d-813360a98beb\"\n  });\n<\/script>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Lesen Sie mehr dar\u00fcber, wie Sie mit KI durch die EU-Taxonomie navigieren k\u00f6nnen<\/h3>\n\n\n\n<p><strong><a href=\"https:\/\/dydon.ai\/navigating-eu-taxonomy-reporting-timeline-kpis-and-best-practices\/\">Navigieren durch die EU-Taxonomie-Berichterstattung: Zeitplan, KPIs und bew\u00e4hrte Praktiken<\/a><\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/dydon.ai\/applying-ai-eu-taxonomy-software-interview-ceo-dr-hans-peter-guellich\/\">Welche Rolle spielt die KI in der EU-Taxonomie-Software? Interview mit unserem CEO Dr. Hans-Peter G\u00fcllich<\/a><\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/dydon.ai\/de\/?p=4720\">EU-Taxonomie leicht gemacht: Deutsche Sparkassen nutzen TAXO TOOL f\u00fcr nachhaltige Finanzierungsprojekte<\/a><\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/dydon.ai\/german-landesbanken-have-opted-for-the-ai-software-taxo-tool-in-combination-with-the-rsu-taxo-master-to-automate-the-eu-taxonomy-reporting\/\">Deutsche Landesbanken haben sich f\u00fcr die KI-Software TAXO TOOL in Kombination mit dem RSU Taxo Master entschieden, um das EU-Taxonomie-Reporting zu automatisieren<\/a><\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/dydon.ai\/eu-taxonomy-software-taxo-tool-testimonial-sparkasse-bremen\/\">EU-Taxonomiesoftware (Taxo Tool) Erfahrungsbericht: Sparkasse Bremen<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Europ\u00e4ische Union befindet sich auf einer ehrgeizigen und notwendigen Reise, um das Zusammenspiel von Wirtschaftswachstum und \u00f6kologischer Nachhaltigkeit neu zu definieren. In ihrem Bestreben, das Wirtschaftswachstum vom Verbrauch nicht erneuerbarer Ressourcen abzukoppeln, hat sich die EU zum Ziel gesetzt, ihren materiellen Fu\u00dfabdruck deutlich zu verringern. Ausgehend von einem Richtwert von 14 Tonnen pro Kopf&#8230;<\/p>\n","protected":false},"author":4,"featured_media":4412,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_show_sidebar_banner":"","_show_download_button":"","footnotes":""},"categories":[9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EU Taxonomy&#039;s Circular Economy Goal: Immobilien und Bauwesen<\/title>\n<meta name=\"description\" content=\"Durch den Einsatz von KI-L\u00f6sungen sind Bau- und Immobilienunternehmen besser in der Lage, die Kriterien der EU-Taxonomie f\u00fcr die Kreislaufwirtschaft zu erf\u00fcllen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EU Taxonomy&#039;s Circular Economy Goal: Immobilien und Bauwesen\" \/>\n<meta property=\"og:description\" content=\"Durch den Einsatz von KI-L\u00f6sungen sind Bau- und Immobilienunternehmen besser in der Lage, die Kriterien der EU-Taxonomie f\u00fcr die Kreislaufwirtschaft zu erf\u00fcllen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-30T10:19:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-06T09:57:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/stg.dydon.ai\/wp-content\/uploads\/2024\/04\/circular-economy-eu-taxonomy-reporting-buildings-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/\",\"url\":\"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/\",\"name\":\"EU Taxonomy's Circular Economy Goal: Immobilien und Bauwesen\",\"isPartOf\":{\"@id\":\"https:\/\/dydon.ai\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dydon.ai\/wp-content\/uploads\/2024\/04\/circular-economy-eu-taxonomy-reporting-buildings-2.jpg\",\"datePublished\":\"2024-04-30T10:19:21+00:00\",\"dateModified\":\"2025-01-06T09:57:51+00:00\",\"author\":{\"@id\":\"https:\/\/dydon.ai\/de\/#\/schema\/person\/b6c03d6c1b49cc12e35fc6f95de28253\"},\"description\":\"Durch den Einsatz von KI-L\u00f6sungen sind Bau- und Immobilienunternehmen besser in der Lage, die Kriterien der EU-Taxonomie f\u00fcr die Kreislaufwirtschaft zu erf\u00fcllen.\",\"breadcrumb\":{\"@id\":\"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/#primaryimage\",\"url\":\"https:\/\/dydon.ai\/wp-content\/uploads\/2024\/04\/circular-economy-eu-taxonomy-reporting-buildings-2.jpg\",\"contentUrl\":\"https:\/\/dydon.ai\/wp-content\/uploads\/2024\/04\/circular-economy-eu-taxonomy-reporting-buildings-2.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dydon.ai\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Das Ziel der EU-Taxonomie f\u00fcr die Kreislaufwirtschaft: Auswirkungen auf Immobilien und Bauwesen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dydon.ai\/de\/#website\",\"url\":\"https:\/\/dydon.ai\/de\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dydon.ai\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dydon.ai\/de\/#\/schema\/person\/b6c03d6c1b49cc12e35fc6f95de28253\",\"name\":\"Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/dydon.ai\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/83720290758f9313e87aa801fc89cf13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/83720290758f9313e87aa801fc89cf13?s=96&d=mm&r=g\",\"caption\":\"Silva\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EU Taxonomy's Circular Economy Goal: Immobilien und Bauwesen","description":"Durch den Einsatz von KI-L\u00f6sungen sind Bau- und Immobilienunternehmen besser in der Lage, die Kriterien der EU-Taxonomie f\u00fcr die Kreislaufwirtschaft zu erf\u00fcllen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/","og_locale":"de_DE","og_type":"article","og_title":"EU Taxonomy's Circular Economy Goal: Immobilien und Bauwesen","og_description":"Durch den Einsatz von KI-L\u00f6sungen sind Bau- und Immobilienunternehmen besser in der Lage, die Kriterien der EU-Taxonomie f\u00fcr die Kreislaufwirtschaft zu erf\u00fcllen.","og_url":"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/","article_published_time":"2024-04-30T10:19:21+00:00","article_modified_time":"2025-01-06T09:57:51+00:00","og_image":[{"width":1920,"height":1080,"url":"http:\/\/stg.dydon.ai\/wp-content\/uploads\/2024\/04\/circular-economy-eu-taxonomy-reporting-buildings-2.jpg","type":"image\/jpeg"}],"author":"Silva","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Silva","Gesch\u00e4tzte Lesezeit":"8 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/","url":"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/","name":"EU Taxonomy's Circular Economy Goal: Immobilien und Bauwesen","isPartOf":{"@id":"https:\/\/dydon.ai\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/#primaryimage"},"image":{"@id":"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/#primaryimage"},"thumbnailUrl":"https:\/\/dydon.ai\/wp-content\/uploads\/2024\/04\/circular-economy-eu-taxonomy-reporting-buildings-2.jpg","datePublished":"2024-04-30T10:19:21+00:00","dateModified":"2025-01-06T09:57:51+00:00","author":{"@id":"https:\/\/dydon.ai\/de\/#\/schema\/person\/b6c03d6c1b49cc12e35fc6f95de28253"},"description":"Durch den Einsatz von KI-L\u00f6sungen sind Bau- und Immobilienunternehmen besser in der Lage, die Kriterien der EU-Taxonomie f\u00fcr die Kreislaufwirtschaft zu erf\u00fcllen.","breadcrumb":{"@id":"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/#primaryimage","url":"https:\/\/dydon.ai\/wp-content\/uploads\/2024\/04\/circular-economy-eu-taxonomy-reporting-buildings-2.jpg","contentUrl":"https:\/\/dydon.ai\/wp-content\/uploads\/2024\/04\/circular-economy-eu-taxonomy-reporting-buildings-2.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/dydon.ai\/de\/das-ziel-der-eu-taxonomie-fuer-die-kreislaufwirtschaft-auswirkungen-auf-immobilien-und-bauwesen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dydon.ai\/de\/"},{"@type":"ListItem","position":2,"name":"Das Ziel der EU-Taxonomie f\u00fcr die Kreislaufwirtschaft: Auswirkungen auf Immobilien und Bauwesen"}]},{"@type":"WebSite","@id":"https:\/\/dydon.ai\/de\/#website","url":"https:\/\/dydon.ai\/de\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dydon.ai\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/dydon.ai\/de\/#\/schema\/person\/b6c03d6c1b49cc12e35fc6f95de28253","name":"Silva","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/dydon.ai\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/83720290758f9313e87aa801fc89cf13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83720290758f9313e87aa801fc89cf13?s=96&d=mm&r=g","caption":"Silva"}}]}},"taxonomy_info":{"category":[{"value":9,"label":"Unkategorisiert"}]},"featured_image_src_large":["https:\/\/dydon.ai\/wp-content\/uploads\/2024\/04\/circular-economy-eu-taxonomy-reporting-buildings-2-1024x576.jpg",1024,576,true],"author_info":{"display_name":"Silva","author_link":"https:\/\/dydon.ai\/de\/author\/silva\/"},"comment_info":0,"category_info":[{"term_id":9,"name":"Unkategorisiert","slug":"unkategorisiert","term_group":0,"term_taxonomy_id":9,"taxonomy":"category","description":"","parent":0,"count":34,"filter":"raw","cat_ID":9,"category_count":34,"category_description":"","cat_name":"Unkategorisiert","category_nicename":"unkategorisiert","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/dydon.ai\/de\/wp-json\/wp\/v2\/posts\/4527"}],"collection":[{"href":"https:\/\/dydon.ai\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dydon.ai\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dydon.ai\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dydon.ai\/de\/wp-json\/wp\/v2\/comments?post=4527"}],"version-history":[{"count":5,"href":"https:\/\/dydon.ai\/de\/wp-json\/wp\/v2\/posts\/4527\/revisions"}],"predecessor-version":[{"id":6038,"href":"https:\/\/dydon.ai\/de\/wp-json\/wp\/v2\/posts\/4527\/revisions\/6038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dydon.ai\/de\/wp-json\/wp\/v2\/media\/4412"}],"wp:attachment":[{"href":"https:\/\/dydon.ai\/de\/wp-json\/wp\/v2\/media?parent=4527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dydon.ai\/de\/wp-json\/wp\/v2\/categories?post=4527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dydon.ai\/de\/wp-json\/wp\/v2\/tags?post=4527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}